{"id":13402,"date":"2021-04-14T17:42:48","date_gmt":"2021-04-14T18:42:48","guid":{"rendered":"https:\/\/siteofnature.com\/przed-moim-oknem\/"},"modified":"2023-06-16T13:15:20","modified_gmt":"2023-06-16T14:15:20","slug":"przed-moim-oknem","status":"publish","type":"post","link":"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/","title":{"rendered":"Przed moim oknem."},"content":{"rendered":"<p>[et_pb_section][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_text]<\/p>\n\n<p class=\"wp-block-paragraph\">Przed oknami mojego mieszkania rosn\u0105 sosny i modrzewie. Ju\u017c w zesz\u0142ym roku para go\u0142\u0119bi <a href=\"https:\/\/en.wikipedia.org\/wiki\/Common_wood_pigeon\" target=\"_blank\" rel=\"noreferrer noopener\">grzywaczy<\/a> zacz\u0119\u0142a budowa\u0107 gniazdo, ale potem si\u0119 podda\u0142a.  Przed oknami mojego mieszkania rosn\u0105 sosny i modrzewie. Ju\u017c w zesz\u0142ym roku para go\u0142\u0119bi grzywaczy zacz\u0119\u0142a budowa\u0107 gniazdo, ale potem si\u0119 podda\u0142a. W tym roku go\u0142\u0119bie zn\u00f3w przylecia\u0142y. Zacz\u0119li budowa\u0107 gniazdo. Samiec od\u0142ama\u0142 ga\u0142\u0105zki modrzewia i przeni\u00f3s\u0142 je przez sosn\u0119.Samica je uk\u0142ada\u0142a. Te zaj\u0119cia by\u0142y bardzo zabawne. Sporo ga\u0142\u0105zek spad\u0142o pod drzewo. Przechodnie pytali, kto \u015bmieci pod drzewami. Budowa zaj\u0119\u0142a oko\u0142o 3 dni. Potem go\u0142\u0119bie grzywacze kolejno siedzia\u0142y na gnie\u017adzie. Gniazdo znajduje si\u0119 tu\u017c nad oknem. \u0141atwo to zaobserwowa\u0107. Mia\u0142y dwa jajka w gnie\u017adzie. Wyl\u0119g odbywa si\u0119 ju\u017c w drugim tygodniu. Osobi\u015bcie staram si\u0119 chroni\u0107 to miejsce przed zagl\u0105daj\u0105cymi tam kotami. Pogoda jest teraz bardzo z\u0142a. Pada drugi dzie\u0144 i jest oko\u0142o +2 stopni. Mam nadziej\u0119, \u017ce wykluj\u0105 si\u0119 piskl\u0119ta. Kiedy to nast\u0105pi, napisz\u0119 w nast\u0119pnym po\u015bcie.                 <\/p>\n\n<div class=\"wp-block-envira-envira-gallery\"><div id=\"envira-gallery-wrap-8744\" class=\"envira-gallery-wrap envira-gallery-theme-base envira-lightbox-theme-base\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><div data-row-height=\"\" data-gallery-theme=\"\" id=\"envira-gallery-8744\" class=\"envira-gallery-public  envira-gallery-4-columns envira-clear enviratope envira-gallery-css-animations\" data-envira-columns=\"4\"><div id=\"envira-gallery-item-8740\" class=\"envira-gallery-item enviratope-item envira-gallery-item-1 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/www.siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7572_opt-1.jpg\" class=\"envira-gallery-8744 envira-gallery-link\" rel=\"enviragallery8744\" title=\"pigeon on the nest\" data-envira-caption=\"pigeon on the nest\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-8740\" class=\"envira-gallery-image envira-gallery-image-1\" data-envira-index=\"1\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7572_opt-1-1024x689-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7572_opt-1-1024x689-640x480.jpg\" data-envira-gallery-id=\"8744\" data-envira-item-id=\"8740\" data-envira-caption=\"pigeon on the nest\" alt=\"pigeon on the nest\" title=\"pigeon on the nest\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7572_opt-1-1024x689-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7572_opt-1-1024x689-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-8741\" class=\"envira-gallery-item enviratope-item envira-gallery-item-2 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/www.siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7575_opt-1.jpg\" class=\"envira-gallery-8744 envira-gallery-link\" rel=\"enviragallery8744\" title=\"pigeon on the nest\" data-envira-caption=\"pigeon on the nest\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-8741\" class=\"envira-gallery-image envira-gallery-image-2\" data-envira-index=\"2\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7575_opt-1-1024x719-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7575_opt-1-1024x719-640x480.jpg\" data-envira-gallery-id=\"8744\" data-envira-item-id=\"8741\" data-envira-caption=\"pigeon on the nest\" alt=\"pigeon on the nest\" title=\"pigeon on the nest\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7575_opt-1-1024x719-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7575_opt-1-1024x719-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-8742\" class=\"envira-gallery-item enviratope-item envira-gallery-item-3 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/www.siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7576_opt-1.jpg\" class=\"envira-gallery-8744 envira-gallery-link\" rel=\"enviragallery8744\" title=\"a male flew in for a change\" data-envira-caption=\"a male flew in for a change\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-8742\" class=\"envira-gallery-image envira-gallery-image-3\" data-envira-index=\"3\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7576_opt-1-1024x641-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7576_opt-1-1024x641-640x480.jpg\" data-envira-gallery-id=\"8744\" data-envira-item-id=\"8742\" data-envira-caption=\"a male flew in for a change\" alt=\"a male flew in for a change\" title=\"a male flew in for a change\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7576_opt-1-1024x641-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7576_opt-1-1024x641-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-8743\" class=\"envira-gallery-item enviratope-item envira-gallery-item-4 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/www.siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7578_opt-1.jpg\" class=\"envira-gallery-8744 envira-gallery-link\" rel=\"enviragallery8744\" title=\"a male flew in for a change\" data-envira-caption=\"a male flew in for a change\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-8743\" class=\"envira-gallery-image envira-gallery-image-4\" data-envira-index=\"4\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7578_opt-1-1024x672-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7578_opt-1-1024x672-640x480.jpg\" data-envira-gallery-id=\"8744\" data-envira-item-id=\"8743\" data-envira-caption=\"a male flew in for a change\" alt=\"a male flew in for a change\" title=\"a male flew in for a change\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7578_opt-1-1024x672-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7578_opt-1-1024x672-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><\/div><\/div><noscript><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7572_opt-1.jpg\" alt=\"pigeon on the nest\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7575_opt-1.jpg\" alt=\"pigeon on the nest\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7576_opt-1.jpg\" alt=\"a male flew in for a change\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/04\/IMG_7578_opt-1.jpg\" alt=\"a male flew in for a change\" \/><\/noscript><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_section et_pb_section_0 et_section_regular\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_pb_row et_pb_row_0 et_pb_row_empty\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_pb_module et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div> Przed oknami mojego mieszkania rosn\u0105 sosny i modrzewie. Ju\u017c w zesz\u0142ym roku para go\u0142\u0119bi grzywaczy zacz\u0119\u0142a budowa\u0107 gniazdo, ale potem si\u0119 podda\u0142a. Przed oknami mojego mieszkania rosn\u0105 sosny i modrzewie. Ju\u017c w zesz\u0142ym roku para go\u0142\u0119bi grzywaczy zacz\u0119\u0142a budowa\u0107 gniazdo, ale potem si\u0119 podda\u0142a. W tym roku go\u0142\u0119bie zn\u00f3w przylecia\u0142y. Zacz\u0119li budowa\u0107 gniazdo. Samiec [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[665],"tags":[732,731],"class_list":["post-13402","post","type-post","status-publish","format-standard","hentry","category-obserwacje-ptakow-pl","tag-columba-palumbus-pl","tag-golab-grzywacz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Site of nature - Przed moim oknem.<\/title>\n<meta name=\"description\" content=\"W tym roku go\u0142\u0119bie zn\u00f3w przylecia\u0142y. Zacz\u0119li budowa\u0107 gniazdo. Samiec od\u0142ama\u0142 ga\u0142\u0105zki modrzewia i przeni\u00f3s\u0142 je przez sosn\u0119.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Site of nature - Przed moim oknem.\" \/>\n<meta property=\"og:description\" content=\"W tym roku go\u0142\u0119bie zn\u00f3w przylecia\u0142y. Zacz\u0119li budowa\u0107 gniazdo. Samiec od\u0142ama\u0142 ga\u0142\u0105zki modrzewia i przeni\u00f3s\u0142 je przez sosn\u0119.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/\" \/>\n<meta property=\"og:site_name\" content=\"Site of nature\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pchmur\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pchmur\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-14T18:42:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-16T14:15:20+00:00\" \/>\n<meta name=\"author\" content=\"Pawe\u0142 Chmur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pawe\u0142 Chmur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/przed-moim-oknem\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/przed-moim-oknem\\\/\"},\"author\":{\"name\":\"Pawe\u0142 Chmur\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\"},\"headline\":\"Przed moim oknem.\",\"datePublished\":\"2021-04-14T18:42:48+00:00\",\"dateModified\":\"2023-06-16T14:15:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/przed-moim-oknem\\\/\"},\"wordCount\":216,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\"},\"keywords\":[\"Columba palumbus\",\"go\u0142\u0105b grzywacz\"],\"articleSection\":[\"obserwacje ptak\u00f3w\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/siteofnature.com\\\/pl\\\/przed-moim-oknem\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/przed-moim-oknem\\\/\",\"url\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/przed-moim-oknem\\\/\",\"name\":\"Site of nature - Przed moim oknem.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#website\"},\"datePublished\":\"2021-04-14T18:42:48+00:00\",\"dateModified\":\"2023-06-16T14:15:20+00:00\",\"description\":\"W tym roku go\u0142\u0119bie zn\u00f3w przylecia\u0142y. Zacz\u0119li budowa\u0107 gniazdo. Samiec od\u0142ama\u0142 ga\u0142\u0105zki modrzewia i przeni\u00f3s\u0142 je przez sosn\u0119.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/przed-moim-oknem\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/siteofnature.com\\\/pl\\\/przed-moim-oknem\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/przed-moim-oknem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Przed moim oknem.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/\",\"name\":\"Site of nature\",\"description\":\"my observations and photos of nature in my area\",\"publisher\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\"},\"alternateName\":\"about nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\",\"name\":\"Pawe\u0142 Chmur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\",\"url\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\",\"contentUrl\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\",\"width\":524,\"height\":524,\"caption\":\"Pawe\u0142 Chmur\"},\"logo\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\"},\"sameAs\":[\"https:\\\/\\\/siteofnature.com\",\"https:\\\/\\\/www.facebook.com\\\/pchmur\"],\"url\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/author\\\/siteofnature\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Site of nature - Przed moim oknem.","description":"W tym roku go\u0142\u0119bie zn\u00f3w przylecia\u0142y. Zacz\u0119li budowa\u0107 gniazdo. Samiec od\u0142ama\u0142 ga\u0142\u0105zki modrzewia i przeni\u00f3s\u0142 je przez sosn\u0119.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/","og_locale":"pl_PL","og_type":"article","og_title":"Site of nature - Przed moim oknem.","og_description":"W tym roku go\u0142\u0119bie zn\u00f3w przylecia\u0142y. Zacz\u0119li budowa\u0107 gniazdo. Samiec od\u0142ama\u0142 ga\u0142\u0105zki modrzewia i przeni\u00f3s\u0142 je przez sosn\u0119.","og_url":"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/","og_site_name":"Site of nature","article_publisher":"https:\/\/www.facebook.com\/pchmur","article_author":"https:\/\/www.facebook.com\/pchmur","article_published_time":"2021-04-14T18:42:48+00:00","article_modified_time":"2023-06-16T14:15:20+00:00","author":"Pawe\u0142 Chmur","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Pawe\u0142 Chmur","Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/#article","isPartOf":{"@id":"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/"},"author":{"name":"Pawe\u0142 Chmur","@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66"},"headline":"Przed moim oknem.","datePublished":"2021-04-14T18:42:48+00:00","dateModified":"2023-06-16T14:15:20+00:00","mainEntityOfPage":{"@id":"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/"},"wordCount":216,"commentCount":0,"publisher":{"@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66"},"keywords":["Columba palumbus","go\u0142\u0105b grzywacz"],"articleSection":["obserwacje ptak\u00f3w"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/","url":"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/","name":"Site of nature - Przed moim oknem.","isPartOf":{"@id":"https:\/\/siteofnature.com\/pl\/en\/#website"},"datePublished":"2021-04-14T18:42:48+00:00","dateModified":"2023-06-16T14:15:20+00:00","description":"W tym roku go\u0142\u0119bie zn\u00f3w przylecia\u0142y. Zacz\u0119li budowa\u0107 gniazdo. Samiec od\u0142ama\u0142 ga\u0142\u0105zki modrzewia i przeni\u00f3s\u0142 je przez sosn\u0119.","breadcrumb":{"@id":"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/siteofnature.com\/pl\/przed-moim-oknem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/siteofnature.com\/pl\/home\/"},{"@type":"ListItem","position":2,"name":"Przed moim oknem."}]},{"@type":"WebSite","@id":"https:\/\/siteofnature.com\/pl\/en\/#website","url":"https:\/\/siteofnature.com\/pl\/en\/","name":"Site of nature","description":"my observations and photos of nature in my area","publisher":{"@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66"},"alternateName":"about nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/siteofnature.com\/pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":["Person","Organization"],"@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66","name":"Pawe\u0142 Chmur","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg","url":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg","contentUrl":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg","width":524,"height":524,"caption":"Pawe\u0142 Chmur"},"logo":{"@id":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg"},"sameAs":["https:\/\/siteofnature.com","https:\/\/www.facebook.com\/pchmur"],"url":"https:\/\/siteofnature.com\/pl\/author\/siteofnature\/"}]}},"_links":{"self":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts\/13402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/comments?post=13402"}],"version-history":[{"count":1,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts\/13402\/revisions"}],"predecessor-version":[{"id":13403,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts\/13402\/revisions\/13403"}],"wp:attachment":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/media?parent=13402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/categories?post=13402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/tags?post=13402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}