{"id":13542,"date":"2020-07-05T16:18:43","date_gmt":"2020-07-05T17:18:43","guid":{"rendered":"https:\/\/siteofnature.com\/mamy-juz-pelnie-lata\/"},"modified":"2023-07-07T08:55:36","modified_gmt":"2023-07-07T09:55:36","slug":"mamy-juz-pelnie-lata","status":"publish","type":"post","link":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/","title":{"rendered":"Mamy ju\u017c pe\u0142ni\u0119 lata."},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.22&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.14.7&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><!-- divi:paragraph --> Nadesz\u0142o lato. Jest pocz\u0105tek lipca. Poniewa\u017c mamy du\u017co opad\u00f3w, wi\u0119c przyroda kwitnie. Sezon na sianokosy, ale wkr\u00f3tce rozpoczn\u0105 si\u0119 \u017cniwa. Ptaki ju\u017c si\u0119 rozmno\u017cy\u0142y i s\u0105 prawie niewidoczne. Nie s\u0142ycha\u0107 ju\u017c ich \u015bpiewu. Jeszcze wczoraj us\u0142ysza\u0142em g\u0142os kuku\u0142ki. My\u015bl\u0119, \u017ce to ostatni raz. Ale za to mo\u017cna zobaczy\u0107 wiele motyli i innych owad\u00f3w.        <\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:envira\/envira-gallery {\"galleryId\":7656,\"title\":\"5-07-20\",\"columns\":\"5\",\"lightbox_theme\":\"base\",\"images\":[{\"status\":\"active\",\"src\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt.jpg\",\"title\":\"view of Rozanystok\",\"link\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt.jpg\",\"alt\":\"from the border with Belarus\",\"caption\":\"\",\"thumb\":\"\",\"id\":7657,\"height\":783,\"width\":1200},{\"status\":\"active\",\"src\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1.jpg\",\"title\":\"village near the border\",\"link\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1.jpg\",\"alt\":\"village near the border\",\"caption\":\"\",\"thumb\":\"\",\"id\":7658,\"height\":801,\"width\":1200},{\"status\":\"active\",\"src\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1.jpg\",\"title\":\"haymaking\",\"link\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1.jpg\",\"alt\":\"haymaking\",\"caption\":\"\",\"thumb\":\"\",\"id\":7659,\"height\":750,\"width\":1200},{\"status\":\"active\",\"src\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt.jpg\",\"title\":\"haymaking\",\"link\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt.jpg\",\"alt\":\"after sunset\",\"caption\":\"\",\"thumb\":\"\",\"id\":7660,\"height\":988,\"width\":1500},{\"status\":\"active\",\"src\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt.jpg\",\"title\":\"village Jaczno\",\"link\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt.jpg\",\"alt\":\"Jaczno village\",\"caption\":\"\",\"thumb\":\"\",\"id\":7661,\"height\":801,\"width\":1200}]} --><\/p>\n<p><!-- \/divi:envira\/envira-gallery --><\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8221;4.14.7&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<div id=\"envira-gallery-wrap-7656\" class=\"envira-gallery-wrap envira-gallery-theme-base envira-lightbox-theme-base\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><div data-row-height=\"\" data-gallery-theme=\"\" id=\"envira-gallery-7656\" class=\"envira-gallery-public  envira-gallery-5-columns envira-clear enviratope envira-gallery-css-animations\" data-envira-columns=\"5\"><div id=\"envira-gallery-item-7657\" class=\"envira-gallery-item enviratope-item envira-gallery-item-1 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt.jpg\" class=\"envira-gallery-7656 envira-gallery-link\" rel=\"enviragallery7656\" title=\"view of Rozanystok\" data-envira-caption=\"view of Rozanystok\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-7657\" class=\"envira-gallery-image envira-gallery-image-1\" data-envira-index=\"1\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt-1024x668-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt-1024x668-640x480.jpg\" data-envira-gallery-id=\"7656\" data-envira-item-id=\"7657\" data-envira-caption=\"view of Rozanystok\" alt=\"from the border with Belarus\" title=\"view of Rozanystok\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt-1024x668-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt-1024x668-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-7658\" class=\"envira-gallery-item enviratope-item envira-gallery-item-2 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1.jpg\" class=\"envira-gallery-7656 envira-gallery-link\" rel=\"enviragallery7656\" title=\"village near the border\" data-envira-caption=\"village near the border\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-7658\" class=\"envira-gallery-image envira-gallery-image-2\" data-envira-index=\"2\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1-1024x684-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1-1024x684-640x480.jpg\" data-envira-gallery-id=\"7656\" data-envira-item-id=\"7658\" data-envira-caption=\"village near the border\" alt=\"village near the border\" title=\"village near the border\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1-1024x684-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1-1024x684-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-7659\" class=\"envira-gallery-item enviratope-item envira-gallery-item-3 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1.jpg\" class=\"envira-gallery-7656 envira-gallery-link\" rel=\"enviragallery7656\" title=\"haymaking\" data-envira-caption=\"haymaking\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-7659\" class=\"envira-gallery-image envira-gallery-image-3\" data-envira-index=\"3\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1-1024x640-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1-1024x640-640x480.jpg\" data-envira-gallery-id=\"7656\" data-envira-item-id=\"7659\" data-envira-caption=\"haymaking\" alt=\"haymaking\" title=\"haymaking\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1-1024x640-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1-1024x640-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-7660\" class=\"envira-gallery-item enviratope-item envira-gallery-item-4 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt.jpg\" class=\"envira-gallery-7656 envira-gallery-link\" rel=\"enviragallery7656\" title=\"haymaking\" data-envira-caption=\"haymaking\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-7660\" class=\"envira-gallery-image envira-gallery-image-4\" data-envira-index=\"4\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt-1024x674-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt-1024x674-640x480.jpg\" data-envira-gallery-id=\"7656\" data-envira-item-id=\"7660\" data-envira-caption=\"haymaking\" alt=\"after sunset\" title=\"haymaking\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt-1024x674-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt-1024x674-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-7661\" class=\"envira-gallery-item enviratope-item envira-gallery-item-5 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt.jpg\" class=\"envira-gallery-7656 envira-gallery-link\" rel=\"enviragallery7656\" title=\"village Jaczno\" data-envira-caption=\"village Jaczno\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-7661\" class=\"envira-gallery-image envira-gallery-image-5\" data-envira-index=\"5\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt-1024x684-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt-1024x684-640x480.jpg\" data-envira-gallery-id=\"7656\" data-envira-item-id=\"7661\" data-envira-caption=\"village Jaczno\" alt=\"Jaczno village\" title=\"village Jaczno\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt-1024x684-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt-1024x684-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><\/div><\/div><noscript><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt.jpg\" alt=\"from the border with Belarus\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1.jpg\" alt=\"village near the border\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1.jpg\" alt=\"haymaking\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt.jpg\" alt=\"after sunset\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt.jpg\" alt=\"Jaczno village\" \/><\/noscript>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nadesz\u0142o lato. Jest pocz\u0105tek lipca. Poniewa\u017c mamy du\u017co opad\u00f3w, wi\u0119c przyroda kwitnie. Sezon na sianokosy, ale wkr\u00f3tce rozpoczn\u0105 si\u0119 \u017cniwa. Ptaki ju\u017c si\u0119 rozmno\u017cy\u0142y i s\u0105 prawie niewidoczne. Nie s\u0142ycha\u0107 ju\u017c ich \u015bpiewu. Jeszcze wczoraj us\u0142ysza\u0142em g\u0142os kuku\u0142ki. My\u015bl\u0119, \u017ce to ostatni raz. Ale za to mo\u017cna zobaczy\u0107 wiele motyli i innych owad\u00f3w. <div id=\"envira-gallery-wrap-7656\" class=\"envira-gallery-wrap envira-gallery-theme-base envira-lightbox-theme-base\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><div data-row-height=\"\" data-gallery-theme=\"\" id=\"envira-gallery-7656\" class=\"envira-gallery-public  envira-gallery-5-columns envira-clear enviratope envira-gallery-css-animations\" data-envira-columns=\"5\"><div id=\"envira-gallery-item-7657\" class=\"envira-gallery-item enviratope-item envira-gallery-item-1 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt.jpg\" class=\"envira-gallery-7656 envira-gallery-link\" rel=\"enviragallery7656\" title=\"view of Rozanystok\" data-envira-caption=\"view of Rozanystok\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-7657\" class=\"envira-gallery-image envira-gallery-image-1\" data-envira-index=\"1\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt-1024x668-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt-1024x668-640x480.jpg\" data-envira-gallery-id=\"7656\" data-envira-item-id=\"7657\" data-envira-caption=\"view of Rozanystok\" alt=\"from the border with Belarus\" title=\"view of Rozanystok\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt-1024x668-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt-1024x668-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-7658\" class=\"envira-gallery-item enviratope-item envira-gallery-item-2 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1.jpg\" class=\"envira-gallery-7656 envira-gallery-link\" rel=\"enviragallery7656\" title=\"village near the border\" data-envira-caption=\"village near the border\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-7658\" class=\"envira-gallery-image envira-gallery-image-2\" data-envira-index=\"2\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1-1024x684-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1-1024x684-640x480.jpg\" data-envira-gallery-id=\"7656\" data-envira-item-id=\"7658\" data-envira-caption=\"village near the border\" alt=\"village near the border\" title=\"village near the border\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1-1024x684-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1-1024x684-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-7659\" class=\"envira-gallery-item enviratope-item envira-gallery-item-3 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1.jpg\" class=\"envira-gallery-7656 envira-gallery-link\" rel=\"enviragallery7656\" title=\"haymaking\" data-envira-caption=\"haymaking\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-7659\" class=\"envira-gallery-image envira-gallery-image-3\" data-envira-index=\"3\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1-1024x640-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1-1024x640-640x480.jpg\" data-envira-gallery-id=\"7656\" data-envira-item-id=\"7659\" data-envira-caption=\"haymaking\" alt=\"haymaking\" title=\"haymaking\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1-1024x640-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1-1024x640-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-7660\" class=\"envira-gallery-item enviratope-item envira-gallery-item-4 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt.jpg\" class=\"envira-gallery-7656 envira-gallery-link\" rel=\"enviragallery7656\" title=\"haymaking\" data-envira-caption=\"haymaking\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-7660\" class=\"envira-gallery-image envira-gallery-image-4\" data-envira-index=\"4\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt-1024x674-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt-1024x674-640x480.jpg\" data-envira-gallery-id=\"7656\" data-envira-item-id=\"7660\" data-envira-caption=\"haymaking\" alt=\"after sunset\" title=\"haymaking\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt-1024x674-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt-1024x674-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-7661\" class=\"envira-gallery-item enviratope-item envira-gallery-item-5 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt.jpg\" class=\"envira-gallery-7656 envira-gallery-link\" rel=\"enviragallery7656\" title=\"village Jaczno\" data-envira-caption=\"village Jaczno\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-7661\" class=\"envira-gallery-image envira-gallery-image-5\" data-envira-index=\"5\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt-1024x684-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt-1024x684-640x480.jpg\" data-envira-gallery-id=\"7656\" data-envira-item-id=\"7661\" data-envira-caption=\"village Jaczno\" alt=\"Jaczno village\" title=\"village Jaczno\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt-1024x684-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt-1024x684-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><\/div><\/div><noscript><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6471_opt.jpg\" alt=\"from the border with Belarus\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6472_opt-1.jpg\" alt=\"village near the border\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6488_opt-1.jpg\" alt=\"haymaking\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt.jpg\" alt=\"after sunset\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6495_opt.jpg\" alt=\"Jaczno village\" \/><\/noscript><\/p>\n","protected":false},"author":1,"featured_media":12046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[672],"tags":[711,685,750],"class_list":["post-13542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krajobrazy-pl","tag-lato","tag-ptaki","tag-zniwa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mamy ju\u017c pe\u0142ni\u0119 lata. - Site of nature<\/title>\n<meta name=\"description\" content=\"Sezon na sianokosy, ale wkr\u00f3tce rozpoczn\u0105 si\u0119 \u017cniwa. Ptaki ju\u017c si\u0119 rozmno\u017cy\u0142y i s\u0105 prawie niewidoczne. Nie s\u0142ycha\u0107 ju\u017c ich \u015bpiewu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1, noarchive\" \/>\n<link rel=\"canonical\" href=\"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"oto mamy pe\u0142ni\u0119 lata\" \/>\n<meta property=\"og:description\" content=\"Sezon na sianokosy, ale wkr\u00f3tce rozpoczn\u0105 si\u0119 \u017cniwa. Ptaki ju\u017c si\u0119 rozmno\u017cy\u0142y i s\u0105 prawie niewidoczne. Nie s\u0142ycha\u0107 ju\u017c ich \u015bpiewu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/\" \/>\n<meta property=\"og:site_name\" content=\"Site of nature\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pchmur\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pchmur\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-05T17:18:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-07T09:55:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt_opt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"791\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pawe\u0142 Chmur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pawe\u0142 Chmur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/\"},\"author\":{\"name\":\"Pawe\u0142 Chmur\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\"},\"headline\":\"Mamy ju\u017c pe\u0142ni\u0119 lata.\",\"datePublished\":\"2020-07-05T17:18:43+00:00\",\"dateModified\":\"2023-07-07T09:55:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/\"},\"wordCount\":167,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\"},\"image\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/IMG_6494_opt_opt.jpg\",\"keywords\":[\"lato\",\"ptaki\",\"\u017cniwa\"],\"articleSection\":[\"krajobrazy\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/\",\"url\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/\",\"name\":\"Mamy ju\u017c pe\u0142ni\u0119 lata. - Site of nature\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/IMG_6494_opt_opt.jpg\",\"datePublished\":\"2020-07-05T17:18:43+00:00\",\"dateModified\":\"2023-07-07T09:55:36+00:00\",\"description\":\"Sezon na sianokosy, ale wkr\u00f3tce rozpoczn\u0105 si\u0119 \u017cniwa. Ptaki ju\u017c si\u0119 rozmno\u017cy\u0142y i s\u0105 prawie niewidoczne. Nie s\u0142ycha\u0107 ju\u017c ich \u015bpiewu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/IMG_6494_opt_opt.jpg\",\"contentUrl\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/IMG_6494_opt_opt.jpg\",\"width\":1200,\"height\":791},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/mamy-juz-pelnie-lata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mamy ju\u017c pe\u0142ni\u0119 lata.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/\",\"name\":\"Site of nature\",\"description\":\"my observations and photos of nature in my area\",\"publisher\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\"},\"alternateName\":\"about nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\",\"name\":\"Pawe\u0142 Chmur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\",\"url\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\",\"contentUrl\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\",\"width\":524,\"height\":524,\"caption\":\"Pawe\u0142 Chmur\"},\"logo\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\"},\"sameAs\":[\"https:\\\/\\\/siteofnature.com\",\"https:\\\/\\\/www.facebook.com\\\/pchmur\"],\"url\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/author\\\/siteofnature\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mamy ju\u017c pe\u0142ni\u0119 lata. - Site of nature","description":"Sezon na sianokosy, ale wkr\u00f3tce rozpoczn\u0105 si\u0119 \u017cniwa. Ptaki ju\u017c si\u0119 rozmno\u017cy\u0142y i s\u0105 prawie niewidoczne. Nie s\u0142ycha\u0107 ju\u017c ich \u015bpiewu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1","archive":"noarchive"},"canonical":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/","og_locale":"pl_PL","og_type":"article","og_title":"oto mamy pe\u0142ni\u0119 lata","og_description":"Sezon na sianokosy, ale wkr\u00f3tce rozpoczn\u0105 si\u0119 \u017cniwa. Ptaki ju\u017c si\u0119 rozmno\u017cy\u0142y i s\u0105 prawie niewidoczne. Nie s\u0142ycha\u0107 ju\u017c ich \u015bpiewu.","og_url":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/","og_site_name":"Site of nature","article_publisher":"https:\/\/www.facebook.com\/pchmur","article_author":"https:\/\/www.facebook.com\/pchmur","article_published_time":"2020-07-05T17:18:43+00:00","article_modified_time":"2023-07-07T09:55:36+00:00","og_image":[{"width":1200,"height":791,"url":"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt_opt.jpg","type":"image\/jpeg"}],"author":"Pawe\u0142 Chmur","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Pawe\u0142 Chmur","Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/#article","isPartOf":{"@id":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/"},"author":{"name":"Pawe\u0142 Chmur","@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66"},"headline":"Mamy ju\u017c pe\u0142ni\u0119 lata.","datePublished":"2020-07-05T17:18:43+00:00","dateModified":"2023-07-07T09:55:36+00:00","mainEntityOfPage":{"@id":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/"},"wordCount":167,"commentCount":0,"publisher":{"@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66"},"image":{"@id":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/#primaryimage"},"thumbnailUrl":"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt_opt.jpg","keywords":["lato","ptaki","\u017cniwa"],"articleSection":["krajobrazy"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/","url":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/","name":"Mamy ju\u017c pe\u0142ni\u0119 lata. - Site of nature","isPartOf":{"@id":"https:\/\/siteofnature.com\/pl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/#primaryimage"},"image":{"@id":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/#primaryimage"},"thumbnailUrl":"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt_opt.jpg","datePublished":"2020-07-05T17:18:43+00:00","dateModified":"2023-07-07T09:55:36+00:00","description":"Sezon na sianokosy, ale wkr\u00f3tce rozpoczn\u0105 si\u0119 \u017cniwa. Ptaki ju\u017c si\u0119 rozmno\u017cy\u0142y i s\u0105 prawie niewidoczne. Nie s\u0142ycha\u0107 ju\u017c ich \u015bpiewu.","breadcrumb":{"@id":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/#primaryimage","url":"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt_opt.jpg","contentUrl":"https:\/\/siteofnature.com\/wp-content\/uploads\/2020\/07\/IMG_6494_opt_opt.jpg","width":1200,"height":791},{"@type":"BreadcrumbList","@id":"https:\/\/siteofnature.com\/pl\/mamy-juz-pelnie-lata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/siteofnature.com\/pl\/home\/"},{"@type":"ListItem","position":2,"name":"Mamy ju\u017c pe\u0142ni\u0119 lata."}]},{"@type":"WebSite","@id":"https:\/\/siteofnature.com\/pl\/en\/#website","url":"https:\/\/siteofnature.com\/pl\/en\/","name":"Site of nature","description":"my observations and photos of nature in my area","publisher":{"@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66"},"alternateName":"about nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/siteofnature.com\/pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":["Person","Organization"],"@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66","name":"Pawe\u0142 Chmur","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg","url":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg","contentUrl":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg","width":524,"height":524,"caption":"Pawe\u0142 Chmur"},"logo":{"@id":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg"},"sameAs":["https:\/\/siteofnature.com","https:\/\/www.facebook.com\/pchmur"],"url":"https:\/\/siteofnature.com\/pl\/author\/siteofnature\/"}]}},"_links":{"self":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts\/13542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/comments?post=13542"}],"version-history":[{"count":6,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts\/13542\/revisions"}],"predecessor-version":[{"id":16198,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts\/13542\/revisions\/16198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/media\/12046"}],"wp:attachment":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/media?parent=13542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/categories?post=13542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/tags?post=13542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}