{"id":15073,"date":"2016-01-03T14:39:03","date_gmt":"2016-01-03T15:39:03","guid":{"rendered":"https:\/\/siteofnature.com\/i-przyszla-zima-2\/"},"modified":"2023-07-09T12:29:52","modified_gmt":"2023-07-09T13:29:52","slug":"i-przyszla-zima-2","status":"publish","type":"post","link":"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/","title":{"rendered":"I przysz\u0142a zima."},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><!-- divi:paragraph --> Na zim\u0119 czekali\u015bmy prawie do ko\u0144ca roku. Grudzie\u0144 by\u0142 najcieplejszy od wielu, wielu lat. Ostatnie 2 dni grudnia przynios\u0142y och\u0142odzenie, ale dzi\u015b mamy prawdziwy mr\u00f3z. W nocy by\u0142o -18 stopni. Zima nie jest kompletna, bo nie ma \u015bniegu. Wszystkie stawy, jeziora, a nawet rzeki by\u0142y pokryte lodem. Wiatr wieje ze wschodu, wi\u0119c mr\u00f3z utrzyma si\u0119 jeszcze d\u0142ugo. Zimuj\u0105ce ptaki koncentruj\u0105 si\u0119 przy karmnikach. C\u00f3\u017c, dni s\u0105 s\u0142oneczne, a kr\u00f3tkie dni wydaj\u0105 si\u0119 d\u0142u\u017csze.        <\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:envira\/envira-gallery {\"galleryId\":8420,\"title\":\"And winter came\",\"columns\":\"3\",\"row_height\":150,\"margins\":\"custom\",\"lightbox_enabled\":1,\"lazyload_enabled\":1,\"lightbox_theme\":\"base\",\"images\":[{\"status\":\"active\",\"src\":\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6516_opt.jpg\",\"title\":\"IMG\\u003cem\\u003e6516\\u003c\/em\\u003eopt\",\"link\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6516_opt.jpg\",\"alt\":\"\",\"caption\":\"\",\"thumb\":\"\",\"id\":4412,\"height\":667,\"width\":1000},{\"status\":\"active\",\"src\":\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6509_opt.jpg\",\"title\":\"IMG\\u003cem\\u003e6509\\u003c\/em\\u003eopt\",\"link\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6509_opt.jpg\",\"alt\":\"\",\"caption\":\"\",\"thumb\":\"\",\"id\":4411,\"height\":667,\"width\":1000},{\"status\":\"active\",\"src\":\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6502_opt.jpg\",\"title\":\"IMG\\u003cem\\u003e6502\\u003c\/em\\u003eopt\",\"link\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6502_opt.jpg\",\"alt\":\"\",\"caption\":\"\",\"thumb\":\"\",\"id\":4410,\"height\":667,\"width\":1000},{\"status\":\"active\",\"src\":\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6492_opt.jpg\",\"title\":\"IMG\\u003cem\\u003e6492\\u003c\/em\\u003eopt\",\"link\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6492_opt.jpg\",\"alt\":\"\",\"caption\":\"\",\"thumb\":\"\",\"id\":4409,\"height\":667,\"width\":1000},{\"status\":\"active\",\"src\":\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6499-_opt.jpg\",\"title\":\"IMG\\u003cem\\u003e6499 \\u003c\/em\\u003eopt\",\"link\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6499-_opt.jpg\",\"alt\":\"\",\"caption\":\"\",\"thumb\":\"\",\"id\":4406,\"height\":684,\"width\":1024},{\"status\":\"active\",\"src\":\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6475_opt.jpg\",\"title\":\"IMG\\u003cem\\u003e6475\\u003c\/em\\u003eopt\",\"link\":\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6475_opt.jpg\",\"alt\":\"\",\"caption\":\"\",\"thumb\":\"\",\"id\":4405,\"height\":684,\"width\":1024}]} --><\/p>\n<div class=\"wp-block-envira-envira-gallery\"><\/div>\n<p><!-- \/divi:envira\/envira-gallery --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<div id=\"envira-gallery-wrap-8420\" class=\"envira-gallery-wrap envira-gallery-theme-base envira-lightbox-theme-base\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><div data-row-height=\"\" data-gallery-theme=\"\" id=\"envira-gallery-8420\" class=\"envira-gallery-public  envira-gallery-3-columns envira-clear enviratope envira-gallery-css-animations\" data-envira-columns=\"3\"><div id=\"envira-gallery-item-4412\" class=\"envira-gallery-item enviratope-item envira-gallery-item-1 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6516_opt.jpg\" class=\"envira-gallery-8420 envira-gallery-link\" rel=\"enviragallery8420\" title=\"IMG&amp;lt;em&amp;gt;6516&amp;lt;\/em&amp;gt;opt\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6516&amp;lt;\/em&amp;gt;opt\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-4412\" class=\"envira-gallery-image envira-gallery-image-1\" data-envira-index=\"1\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6516_opt-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6516_opt-640x480.jpg\" data-envira-gallery-id=\"8420\" data-envira-item-id=\"4412\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6516&amp;lt;\/em&amp;gt;opt\" alt=\"\" title=\"IMG&amp;amp;lt;em&amp;amp;gt;6516&amp;amp;lt;\/em&amp;amp;gt;opt\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6516_opt-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6516_opt-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-4411\" class=\"envira-gallery-item enviratope-item envira-gallery-item-2 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6509_opt.jpg\" class=\"envira-gallery-8420 envira-gallery-link\" rel=\"enviragallery8420\" title=\"IMG&amp;lt;em&amp;gt;6509&amp;lt;\/em&amp;gt;opt\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6509&amp;lt;\/em&amp;gt;opt\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-4411\" class=\"envira-gallery-image envira-gallery-image-2\" data-envira-index=\"2\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6509_opt-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6509_opt-640x480.jpg\" data-envira-gallery-id=\"8420\" data-envira-item-id=\"4411\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6509&amp;lt;\/em&amp;gt;opt\" alt=\"\" title=\"IMG&amp;amp;lt;em&amp;amp;gt;6509&amp;amp;lt;\/em&amp;amp;gt;opt\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6509_opt-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6509_opt-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-4410\" class=\"envira-gallery-item enviratope-item envira-gallery-item-3 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6502_opt.jpg\" class=\"envira-gallery-8420 envira-gallery-link\" rel=\"enviragallery8420\" title=\"IMG&amp;lt;em&amp;gt;6502&amp;lt;\/em&amp;gt;opt\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6502&amp;lt;\/em&amp;gt;opt\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-4410\" class=\"envira-gallery-image envira-gallery-image-3\" data-envira-index=\"3\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6502_opt-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6502_opt-640x480.jpg\" data-envira-gallery-id=\"8420\" data-envira-item-id=\"4410\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6502&amp;lt;\/em&amp;gt;opt\" alt=\"\" title=\"IMG&amp;amp;lt;em&amp;amp;gt;6502&amp;amp;lt;\/em&amp;amp;gt;opt\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6502_opt-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6502_opt-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-4409\" class=\"envira-gallery-item enviratope-item envira-gallery-item-4 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6492_opt.jpg\" class=\"envira-gallery-8420 envira-gallery-link\" rel=\"enviragallery8420\" title=\"IMG&amp;lt;em&amp;gt;6492&amp;lt;\/em&amp;gt;opt\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6492&amp;lt;\/em&amp;gt;opt\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-4409\" class=\"envira-gallery-image envira-gallery-image-4\" data-envira-index=\"4\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6492_opt-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6492_opt-640x480.jpg\" data-envira-gallery-id=\"8420\" data-envira-item-id=\"4409\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6492&amp;lt;\/em&amp;gt;opt\" alt=\"\" title=\"IMG&amp;amp;lt;em&amp;amp;gt;6492&amp;amp;lt;\/em&amp;amp;gt;opt\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6492_opt-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6492_opt-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-4406\" class=\"envira-gallery-item enviratope-item envira-gallery-item-5 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6499-_opt.jpg\" class=\"envira-gallery-8420 envira-gallery-link\" rel=\"enviragallery8420\" title=\"IMG&amp;lt;em&amp;gt;6499 &amp;lt;\/em&amp;gt;opt\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6499 &amp;lt;\/em&amp;gt;opt\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-4406\" class=\"envira-gallery-image envira-gallery-image-5\" data-envira-index=\"5\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6499-_opt-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6499-_opt-640x480.jpg\" data-envira-gallery-id=\"8420\" data-envira-item-id=\"4406\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6499 &amp;lt;\/em&amp;gt;opt\" alt=\"\" title=\"IMG&amp;amp;lt;em&amp;amp;gt;6499 &amp;amp;lt;\/em&amp;amp;gt;opt\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6499-_opt-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6499-_opt-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-4405\" class=\"envira-gallery-item enviratope-item envira-gallery-item-6 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"http:\/\/www.siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6475_opt.jpg\" class=\"envira-gallery-8420 envira-gallery-link\" rel=\"enviragallery8420\" title=\"IMG&amp;lt;em&amp;gt;6475&amp;lt;\/em&amp;gt;opt\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6475&amp;lt;\/em&amp;gt;opt\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-4405\" class=\"envira-gallery-image envira-gallery-image-6\" data-envira-index=\"6\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6475_opt-640x480.jpg\" data-envira-src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6475_opt-640x480.jpg\" data-envira-gallery-id=\"8420\" data-envira-item-id=\"4405\" data-envira-caption=\"IMG&amp;lt;em&amp;gt;6475&amp;lt;\/em&amp;gt;opt\" alt=\"\" title=\"IMG&amp;amp;lt;em&amp;amp;gt;6475&amp;amp;lt;\/em&amp;amp;gt;opt\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6475_opt-640x480.jpg 400w,https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6475_opt-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><\/div><\/div><noscript><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6516_opt.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6509_opt.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6502_opt.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6492_opt.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6499-_opt.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/siteofnature.com\/wp-content\/uploads\/2016\/01\/IMG_6475_opt.jpg\" alt=\"\" \/><\/noscript>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na zim\u0119 czekali\u015bmy prawie do ko\u0144ca roku. Grudzie\u0144 by\u0142 najcieplejszy od wielu, wielu lat. Ostatnie 2 dni grudnia przynios\u0142y och\u0142odzenie, ale dzi\u015b mamy prawdziwy mr\u00f3z. W nocy by\u0142o -18 stopni. Zima nie jest kompletna, bo nie ma \u015bniegu. Wszystkie stawy, jeziora, a nawet rzeki by\u0142y pokryte lodem. Wiatr wieje ze wschodu, wi\u0119c mr\u00f3z utrzyma si\u0119 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[668],"tags":[811,871],"class_list":["post-15073","post","type-post","status-publish","format-standard","hentry","category-warunki-fotografowania","tag-mroz","tag-zima-pl"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I przysz\u0142a zima. - Site of nature<\/title>\n<meta name=\"description\" content=\"przysz\u0142a zima Ostatnie 2 dni grudnia przynios\u0142y och\u0142odzenie, ale dzi\u015b mamy prawdziwy mr\u00f3z. W nocy by\u0142o -18 stopni. Zima nie jest kompletna,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I przysz\u0142a zima. - Site of nature\" \/>\n<meta property=\"og:description\" content=\"przysz\u0142a zima Ostatnie 2 dni grudnia przynios\u0142y och\u0142odzenie, ale dzi\u015b mamy prawdziwy mr\u00f3z. W nocy by\u0142o -18 stopni. Zima nie jest kompletna,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Site of nature\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pchmur\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pchmur\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-03T15:39:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-09T13:29:52+00:00\" \/>\n<meta name=\"author\" content=\"Pawe\u0142 Chmur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pawe\u0142 Chmur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/i-przyszla-zima-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/i-przyszla-zima-2\\\/\"},\"author\":{\"name\":\"Pawe\u0142 Chmur\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\"},\"headline\":\"I przysz\u0142a zima.\",\"datePublished\":\"2016-01-03T15:39:03+00:00\",\"dateModified\":\"2023-07-09T13:29:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/i-przyszla-zima-2\\\/\"},\"wordCount\":184,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\"},\"keywords\":[\"mr\u00f3z\",\"zima\"],\"articleSection\":[\"warunki fotografowania\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/siteofnature.com\\\/pl\\\/i-przyszla-zima-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/i-przyszla-zima-2\\\/\",\"url\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/i-przyszla-zima-2\\\/\",\"name\":\"I przysz\u0142a zima. - Site of nature\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#website\"},\"datePublished\":\"2016-01-03T15:39:03+00:00\",\"dateModified\":\"2023-07-09T13:29:52+00:00\",\"description\":\"przysz\u0142a zima Ostatnie 2 dni grudnia przynios\u0142y och\u0142odzenie, ale dzi\u015b mamy prawdziwy mr\u00f3z. W nocy by\u0142o -18 stopni. Zima nie jest kompletna,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/i-przyszla-zima-2\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/siteofnature.com\\\/pl\\\/i-przyszla-zima-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/i-przyszla-zima-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I przysz\u0142a zima.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/\",\"name\":\"Site of nature\",\"description\":\"my observations and photos of nature in my area\",\"publisher\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\"},\"alternateName\":\"about nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/en\\\/#\\\/schema\\\/person\\\/5ed3d9d3b6bef0c7d37023966e2c0d66\",\"name\":\"Pawe\u0142 Chmur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\",\"url\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\",\"contentUrl\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\",\"width\":524,\"height\":524,\"caption\":\"Pawe\u0142 Chmur\"},\"logo\":{\"@id\":\"https:\\\/\\\/siteofnature.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1625770_1074626285927938_5128424736839005493_n.jpg\"},\"sameAs\":[\"https:\\\/\\\/siteofnature.com\",\"https:\\\/\\\/www.facebook.com\\\/pchmur\"],\"url\":\"https:\\\/\\\/siteofnature.com\\\/pl\\\/author\\\/siteofnature\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I przysz\u0142a zima. - Site of nature","description":"przysz\u0142a zima Ostatnie 2 dni grudnia przynios\u0142y och\u0142odzenie, ale dzi\u015b mamy prawdziwy mr\u00f3z. W nocy by\u0142o -18 stopni. Zima nie jest kompletna,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/","og_locale":"pl_PL","og_type":"article","og_title":"I przysz\u0142a zima. - Site of nature","og_description":"przysz\u0142a zima Ostatnie 2 dni grudnia przynios\u0142y och\u0142odzenie, ale dzi\u015b mamy prawdziwy mr\u00f3z. W nocy by\u0142o -18 stopni. Zima nie jest kompletna,","og_url":"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/","og_site_name":"Site of nature","article_publisher":"https:\/\/www.facebook.com\/pchmur","article_author":"https:\/\/www.facebook.com\/pchmur","article_published_time":"2016-01-03T15:39:03+00:00","article_modified_time":"2023-07-09T13:29:52+00:00","author":"Pawe\u0142 Chmur","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Pawe\u0142 Chmur","Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/#article","isPartOf":{"@id":"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/"},"author":{"name":"Pawe\u0142 Chmur","@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66"},"headline":"I przysz\u0142a zima.","datePublished":"2016-01-03T15:39:03+00:00","dateModified":"2023-07-09T13:29:52+00:00","mainEntityOfPage":{"@id":"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/"},"wordCount":184,"commentCount":0,"publisher":{"@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66"},"keywords":["mr\u00f3z","zima"],"articleSection":["warunki fotografowania"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/","url":"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/","name":"I przysz\u0142a zima. - Site of nature","isPartOf":{"@id":"https:\/\/siteofnature.com\/pl\/en\/#website"},"datePublished":"2016-01-03T15:39:03+00:00","dateModified":"2023-07-09T13:29:52+00:00","description":"przysz\u0142a zima Ostatnie 2 dni grudnia przynios\u0142y och\u0142odzenie, ale dzi\u015b mamy prawdziwy mr\u00f3z. W nocy by\u0142o -18 stopni. Zima nie jest kompletna,","breadcrumb":{"@id":"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/siteofnature.com\/pl\/i-przyszla-zima-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/siteofnature.com\/pl\/home\/"},{"@type":"ListItem","position":2,"name":"I przysz\u0142a zima."}]},{"@type":"WebSite","@id":"https:\/\/siteofnature.com\/pl\/en\/#website","url":"https:\/\/siteofnature.com\/pl\/en\/","name":"Site of nature","description":"my observations and photos of nature in my area","publisher":{"@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66"},"alternateName":"about nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/siteofnature.com\/pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":["Person","Organization"],"@id":"https:\/\/siteofnature.com\/pl\/en\/#\/schema\/person\/5ed3d9d3b6bef0c7d37023966e2c0d66","name":"Pawe\u0142 Chmur","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg","url":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg","contentUrl":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg","width":524,"height":524,"caption":"Pawe\u0142 Chmur"},"logo":{"@id":"https:\/\/siteofnature.com\/wp-content\/uploads\/2021\/01\/1625770_1074626285927938_5128424736839005493_n.jpg"},"sameAs":["https:\/\/siteofnature.com","https:\/\/www.facebook.com\/pchmur"],"url":"https:\/\/siteofnature.com\/pl\/author\/siteofnature\/"}]}},"_links":{"self":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts\/15073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/comments?post=15073"}],"version-history":[{"count":4,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts\/15073\/revisions"}],"predecessor-version":[{"id":16476,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/posts\/15073\/revisions\/16476"}],"wp:attachment":[{"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/media?parent=15073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/categories?post=15073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/siteofnature.com\/pl\/wp-json\/wp\/v2\/tags?post=15073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}